{"id":3260,"date":"2024-10-25T09:34:29","date_gmt":"2024-10-25T07:34:29","guid":{"rendered":"https:\/\/www.interfjord.dk\/kilometerbasierte-und-co2-differenzierte-strassenmaut-fuer-lastwagen\/"},"modified":"2024-10-25T09:34:29","modified_gmt":"2024-10-25T07:34:29","slug":"kilometerbasierte-und-co2-differenzierte-strassenmaut-fuer-lastwagen","status":"publish","type":"post","link":"https:\/\/www.interfjord.dk\/de\/kilometerbasierte-und-co2-differenzierte-strassenmaut-fuer-lastwagen\/","title":{"rendered":"Kilometerbasierte und CO2-differenzierte Stra\u00dfenmaut f\u00fcr Lastwagen"},"content":{"rendered":"<p>Liebe Kundin, lieber Kunde,<\/p>\n<p>&nbsp;<\/p>\n<p>Ab dem 1. Januar 2025 m\u00fcssen Lkw mit einem Gewicht von 12 Tonnen und mehr eine Geb\u00fchr zahlen, um auf den meisten Staatsstra\u00dfen und Teilen des kommunalen Stra\u00dfennetzes (etwa 10.900 km) zu fahren.<\/p>\n<p>Es wird gesch\u00e4tzt, dass dies etwa 75 Prozent der insgesamt mit Lkw gefahrenen Kilometer abdeckt.<\/p>\n<p>Wir als Lieferant sind gezwungen, diese Kosten an unsere Kunden weiterzugeben, und wir werden uns bem\u00fchen, diese auf ein Minimum zu reduzieren.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Details zu dieser neuen kilometerbasierten und CO2-differenzierten Stra\u00dfenmaut f\u00fcr Lkw k\u00f6nnen auf der offiziellen d\u00e4nischen Website gefunden werden: <a href=\"https:\/\/vejafgifter.dk\/\">Vejafgifter.dk<\/a><\/p>\n<p>Wir werden mit weiteren Details zur\u00fcckkommen, sobald wir einen vollst\u00e4ndigen \u00dcberblick \u00fcber diese Kosten haben.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir hoffen auf Ihr Verst\u00e4ndnis in dieser Situation.<\/p>\n<p>Bitte wenden Sie sich bei Fragen gerne an Ihre gewohnte Kontaktperson bei INTERFJORD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Kundin, lieber Kunde, &nbsp; Ab dem 1. Januar 2025 m\u00fcssen Lkw mit einem Gewicht von 12 Tonnen und mehr eine Geb\u00fchr zahlen, um auf den meisten Staatsstra\u00dfen und Teilen des kommunalen Stra\u00dfennetzes (etwa 10.900 km) zu fahren. Es wird gesch\u00e4tzt, dass dies etwa 75 Prozent der insgesamt mit Lkw gefahrenen Kilometer abdeckt. Wir als [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-3260","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/posts\/3260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/comments?post=3260"}],"version-history":[{"count":0,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/posts\/3260\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/media?parent=3260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/categories?post=3260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/tags?post=3260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}