{"id":3095,"date":"2025-02-25T14:40:11","date_gmt":"2025-02-25T13:40:11","guid":{"rendered":"https:\/\/www.interfjord.dk\/nuetzliche-informationen\/zahlungsbedingungen\/"},"modified":"2025-04-14T11:24:01","modified_gmt":"2025-04-14T09:24:01","slug":"zahlungsbedingungen","status":"publish","type":"page","link":"https:\/\/www.interfjord.dk\/de\/nuetzliche-informationen\/zahlungsbedingungen\/","title":{"rendered":"Zahlungsbedingungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3095\" class=\"elementor elementor-3095 elementor-677\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d319fb3 e-con-full e-flex e-con e-parent\" data-id=\"d319fb3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21bbc4c elementor-widget elementor-widget-template\" data-id=\"21bbc4c\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"4182\" class=\"elementor elementor-4182 elementor-1466\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9f9378 e-con-full e-flex e-con e-parent\" data-id=\"c9f9378\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2980e5d e-con-full e-flex e-con e-child\" data-id=\"2980e5d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb82045 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb82045\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">N\u00fctzliche Informationen<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576316d elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"576316d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"640\" src=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy.png\" class=\"attachment-full size-full wp-image-841\" alt=\"\" srcset=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy.png 2560w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy-300x75.png 300w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy-1024x256.png 1024w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy-768x192.png 768w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy-1536x384.png 1536w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/Realistic-without-logo-copy-2048x512.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-954580f e-con-full e-flex e-con e-parent\" data-id=\"954580f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a00a3fc e-con-full e-flex e-con e-child\" data-id=\"a00a3fc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7fdc274 e-con-full e-flex e-con e-child\" data-id=\"7fdc274\" data-element_type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:185,&quot;sticky_effects_offset&quot;:80,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;],&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56ae831 elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"56ae831\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;full_width&quot;:&quot;stretch&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-overline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-56ae831\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2195\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/kapacitetstillaeg-paa-express-og-economy-forsendelser\/\" class=\"elementor-item\">Kapazit\u00e4tszuschlag f\u00fcr Express- und Economy-Sendungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2196\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/olietillaeg\/\" class=\"elementor-item\">\u00d6laufschlag<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2194\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/iso-certificering\/\" class=\"elementor-item\">ISO-Zertifizierung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2189\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/emballeringsguide\/\" class=\"elementor-item\">Verpackungsleitfaden<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2188\"><a rel=\"privacy-policy\" href=\"https:\/\/www.interfjord.dk\/nyttig-info\/datapolitik\/\" class=\"elementor-item\">Datenschutzrichtlinie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2192\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/foedevarestyrelsen\/\" class=\"elementor-item\">Lebensmitteldirektion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2191\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/farligt-gods\/\" class=\"elementor-item\">Gefahrgut<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2190\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/eur-paller\/\" class=\"elementor-item\">EUR-Paletten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2184\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betalingsbetingelser\/\" class=\"elementor-item\">Zahlungsbedingungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2193\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/inco-terms-2010\/\" class=\"elementor-item\">Inco Terms 2010<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2186\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betingelser-sea-freight\/\" class=\"elementor-item\">Bedingungen Seefracht<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2185\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betingelser-air-freight\/\" class=\"elementor-item\">Bedingungen Luftfracht<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2199\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/vareforsikring\/\" class=\"elementor-item\">Warenversicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2187\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/code-of-conduct\/\" class=\"elementor-item\">Verhaltenskodex<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2183\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/ats\/\" class=\"elementor-item\">ATS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2197\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/sponsoraftaler\/\" class=\"elementor-item\">Sponsorenvereinbarungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2198\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/teamviewer\/\" class=\"elementor-item\">Teamviewer<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-56ae831\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2195\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/kapacitetstillaeg-paa-express-og-economy-forsendelser\/\" class=\"elementor-item\" tabindex=\"-1\">Kapazit\u00e4tszuschlag f\u00fcr Express- und Economy-Sendungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2196\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/olietillaeg\/\" class=\"elementor-item\" tabindex=\"-1\">\u00d6laufschlag<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2194\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/iso-certificering\/\" class=\"elementor-item\" tabindex=\"-1\">ISO-Zertifizierung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2189\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/emballeringsguide\/\" class=\"elementor-item\" tabindex=\"-1\">Verpackungsleitfaden<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2188\"><a rel=\"privacy-policy\" href=\"https:\/\/www.interfjord.dk\/nyttig-info\/datapolitik\/\" class=\"elementor-item\" tabindex=\"-1\">Datenschutzrichtlinie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2192\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/foedevarestyrelsen\/\" class=\"elementor-item\" tabindex=\"-1\">Lebensmitteldirektion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2191\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/farligt-gods\/\" class=\"elementor-item\" tabindex=\"-1\">Gefahrgut<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2190\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/eur-paller\/\" class=\"elementor-item\" tabindex=\"-1\">EUR-Paletten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2184\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betalingsbetingelser\/\" class=\"elementor-item\" tabindex=\"-1\">Zahlungsbedingungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2193\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/inco-terms-2010\/\" class=\"elementor-item\" tabindex=\"-1\">Inco Terms 2010<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2186\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betingelser-sea-freight\/\" class=\"elementor-item\" tabindex=\"-1\">Bedingungen Seefracht<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2185\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/betingelser-air-freight\/\" class=\"elementor-item\" tabindex=\"-1\">Bedingungen Luftfracht<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2199\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/vareforsikring\/\" class=\"elementor-item\" tabindex=\"-1\">Warenversicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2187\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/code-of-conduct\/\" class=\"elementor-item\" tabindex=\"-1\">Verhaltenskodex<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2183\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/ats\/\" class=\"elementor-item\" tabindex=\"-1\">ATS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2197\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/sponsoraftaler\/\" class=\"elementor-item\" tabindex=\"-1\">Sponsorenvereinbarungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2198\"><a href=\"https:\/\/www.interfjord.dk\/nyttig-info\/teamviewer\/\" class=\"elementor-item\" tabindex=\"-1\">Teamviewer<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-537e9d3 e-con-full e-flex e-con e-child\" data-id=\"537e9d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff931f5 elementor-widget elementor-widget-text-editor\" data-id=\"ff931f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zahlungsbedingungen gem\u00e4\u00df Vereinbarung. Bei \u00dcberschreitung berechnen wir 2 % Zinsen pro Monat. <br><br>Alle Preise basieren auf den geltenden Tageskursen und \u00d6lpreisen. Unvorhergesehene Geb\u00fchren und Preiserh\u00f6hungen werden separat berechnet. <br><br>Wir setzen einen freien und ungehinderten Transportablauf sowie die M\u00f6glichkeit des Transporteurs f\u00fcr eine angemessene Planung der Lade- und Entladezeiten voraus.<br><br>Spezielle Lieferanforderungen seitens des Empf\u00e4ngers und au\u00dfergew\u00f6hnlicher Zeitaufwand bei der Zollabfertigung innerhalb der EU werden separat berechnet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a2b67d e-con-full e-flex e-con e-parent\" data-id=\"3a2b67d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11af1d4 elementor-widget elementor-widget-template\" data-id=\"11af1d4\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"1350\" class=\"elementor elementor-1350\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1265c21 e-con-full e-flex e-con e-parent\" data-id=\"1265c21\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a3e11a e-con-full e-flex e-con e-child\" data-id=\"2a3e11a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8621e elementor-widget elementor-widget-image\" data-id=\"cc8621e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1138\" height=\"1154\" src=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_1.jpg\" class=\"attachment-full size-full wp-image-1294\" alt=\"\" srcset=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_1.jpg 1138w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_1-296x300.jpg 296w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_1-1010x1024.jpg 1010w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_1-768x779.jpg 768w\" sizes=\"(max-width: 1138px) 100vw, 1138px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dcf2d9 e-con-full e-flex e-con e-child\" data-id=\"2dcf2d9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d92d8 elementor-widget elementor-widget-image\" data-id=\"23d92d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1138\" height=\"1154\" src=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_2.jpg\" class=\"attachment-full size-full wp-image-1295\" alt=\"\" srcset=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_2.jpg 1138w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_2-296x300.jpg 296w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_2-1010x1024.jpg 1010w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_2-768x779.jpg 768w\" sizes=\"(max-width: 1138px) 100vw, 1138px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a834194 e-con-full e-flex e-con e-child\" data-id=\"a834194\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab00384 elementor-widget elementor-widget-image\" data-id=\"ab00384\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1138\" height=\"1154\" src=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_3.jpg\" class=\"attachment-full size-full wp-image-1296\" alt=\"\" srcset=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_3.jpg 1138w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_3-296x300.jpg 296w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_3-1010x1024.jpg 1010w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_3-768x779.jpg 768w\" sizes=\"(max-width: 1138px) 100vw, 1138px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f46b1fe e-con-full e-flex e-con e-child\" data-id=\"f46b1fe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec7542 elementor-widget elementor-widget-image\" data-id=\"4ec7542\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1138\" height=\"1154\" src=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_4.jpg\" class=\"attachment-full size-full wp-image-1297\" alt=\"\" srcset=\"https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_4.jpg 1138w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_4-296x300.jpg 296w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_4-1010x1024.jpg 1010w, https:\/\/www.interfjord.dk\/wp-content\/uploads\/2025\/02\/B2_4-768x779.jpg 768w\" sizes=\"(max-width: 1138px) 100vw, 1138px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zahlungsbedingungen gem\u00e4\u00df Vereinbarung. Bei \u00dcberschreitung berechnen wir 2 % Zinsen pro Monat. Alle Preise basieren auf den geltenden Tageskursen und \u00d6lpreisen. Unvorhergesehene Geb\u00fchren und Preiserh\u00f6hungen werden separat berechnet. Wir setzen einen freien und ungehinderten Transportablauf sowie die M\u00f6glichkeit des Transporteurs f\u00fcr eine angemessene Planung der Lade- und Entladezeiten voraus. Spezielle Lieferanforderungen seitens des Empf\u00e4ngers und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2989,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3095","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/pages\/3095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/comments?post=3095"}],"version-history":[{"count":2,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/pages\/3095\/revisions"}],"predecessor-version":[{"id":3727,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/pages\/3095\/revisions\/3727"}],"up":[{"embeddable":true,"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/pages\/2989"}],"wp:attachment":[{"href":"https:\/\/www.interfjord.dk\/de\/wp-json\/wp\/v2\/media?parent=3095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}